{"id":3982,"count":1,"description":"","link":"https:\/\/uctr-gmbh.de\/en\/day\/pampalo-mine-operations\/","name":"Pampalo mine operations","slug":"pampalo-mine-operations","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pampalo mine operations Archives - UNIVERSAL Chemical Trading GmbH<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pampalo mine operations Archives - UNIVERSAL Chemical Trading GmbH\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uctr-gmbh.de\/en\/day\/pampalo-mine-operations\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIVERSAL Chemical Trading GmbH\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/uctr-gmbh.de\\\/tag\\\/pampalo-mine-operations\\\/\",\"url\":\"https:\\\/\\\/uctr-gmbh.de\\\/tag\\\/pampalo-mine-operations\\\/\",\"name\":\"Pampalo mine operations Archives - UNIVERSAL Chemical Trading GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uctr-gmbh.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uctr-gmbh.de\\\/tag\\\/pampalo-mine-operations\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uctr-gmbh.de\\\/tag\\\/pampalo-mine-operations\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uctr-gmbh.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pampalo mine operations\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uctr-gmbh.de\\\/#website\",\"url\":\"https:\\\/\\\/uctr-gmbh.de\\\/\",\"name\":\"UNIVERSAL Chemical Trading GmbH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uctr-gmbh.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pampalo mine operations Archives - UNIVERSAL Chemical Trading GmbH","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Pampalo mine operations Archives - UNIVERSAL Chemical Trading GmbH","og_url":"https:\/\/uctr-gmbh.de\/en\/day\/pampalo-mine-operations\/","og_site_name":"UNIVERSAL Chemical Trading GmbH","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/uctr-gmbh.de\/tag\/pampalo-mine-operations\/","url":"https:\/\/uctr-gmbh.de\/tag\/pampalo-mine-operations\/","name":"Pampalo mine operations Archives - UNIVERSAL Chemical Trading GmbH","isPartOf":{"@id":"https:\/\/uctr-gmbh.de\/#website"},"breadcrumb":{"@id":"https:\/\/uctr-gmbh.de\/tag\/pampalo-mine-operations\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/uctr-gmbh.de\/tag\/pampalo-mine-operations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uctr-gmbh.de\/"},{"@type":"ListItem","position":2,"name":"Pampalo mine operations"}]},{"@type":"WebSite","@id":"https:\/\/uctr-gmbh.de\/#website","url":"https:\/\/uctr-gmbh.de\/","name":"UNIVERSAL Chemical Trading GmbH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uctr-gmbh.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/uctr-gmbh.de\/en\/wp-json\/wp\/v2\/tags\/3982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uctr-gmbh.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/uctr-gmbh.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/uctr-gmbh.de\/en\/wp-json\/wp\/v2\/posts?tags=3982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}