{"id":1423,"count":1,"description":"","link":"https:\/\/uctr-gmbh.de\/uk\/\u0434\u0435\u043d\u044c\/oko-west-project\/","name":"Oko West Project","slug":"oko-west-project","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oko West Project Archives - UNIVERSAL Chemical Trading GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uctr-gmbh.de\/uk\/\u0434\u0435\u043d\u044c\/oko-west-project\/\" \/>\n<meta property=\"og:locale\" content=\"uk_UA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oko West Project Archives - UNIVERSAL Chemical Trading GmbH\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uctr-gmbh.de\/uk\/\u0434\u0435\u043d\u044c\/oko-west-project\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIVERSAL Chemical Trading GmbH\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/uctr-gmbh.de\\\/tag\\\/oko-west-project\\\/\",\"url\":\"https:\\\/\\\/uctr-gmbh.de\\\/tag\\\/oko-west-project\\\/\",\"name\":\"Oko West Project Archives - UNIVERSAL Chemical Trading GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uctr-gmbh.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uctr-gmbh.de\\\/tag\\\/oko-west-project\\\/#breadcrumb\"},\"inLanguage\":\"uk\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uctr-gmbh.de\\\/tag\\\/oko-west-project\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uctr-gmbh.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oko West Project\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uctr-gmbh.de\\\/#website\",\"url\":\"https:\\\/\\\/uctr-gmbh.de\\\/\",\"name\":\"UNIVERSAL Chemical Trading GmbH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uctr-gmbh.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"uk\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oko West Project Archives - UNIVERSAL Chemical Trading GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uctr-gmbh.de\/uk\/\u0434\u0435\u043d\u044c\/oko-west-project\/","og_locale":"uk_UA","og_type":"article","og_title":"Oko West Project Archives - UNIVERSAL Chemical Trading GmbH","og_url":"https:\/\/uctr-gmbh.de\/uk\/\u0434\u0435\u043d\u044c\/oko-west-project\/","og_site_name":"UNIVERSAL Chemical Trading GmbH","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/uctr-gmbh.de\/tag\/oko-west-project\/","url":"https:\/\/uctr-gmbh.de\/tag\/oko-west-project\/","name":"Oko West Project Archives - UNIVERSAL Chemical Trading GmbH","isPartOf":{"@id":"https:\/\/uctr-gmbh.de\/#website"},"breadcrumb":{"@id":"https:\/\/uctr-gmbh.de\/tag\/oko-west-project\/#breadcrumb"},"inLanguage":"uk"},{"@type":"BreadcrumbList","@id":"https:\/\/uctr-gmbh.de\/tag\/oko-west-project\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uctr-gmbh.de\/"},{"@type":"ListItem","position":2,"name":"Oko West Project"}]},{"@type":"WebSite","@id":"https:\/\/uctr-gmbh.de\/#website","url":"https:\/\/uctr-gmbh.de\/","name":"UNIVERSAL Chemical Trading GmbH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uctr-gmbh.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"uk"}]}},"_links":{"self":[{"href":"https:\/\/uctr-gmbh.de\/uk\/wp-json\/wp\/v2\/tags\/1423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uctr-gmbh.de\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/uctr-gmbh.de\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/uctr-gmbh.de\/uk\/wp-json\/wp\/v2\/posts?tags=1423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}